{"id":1047,"date":"2024-02-26T09:27:33","date_gmt":"2024-02-26T08:27:33","guid":{"rendered":"https:\/\/food-pol.pl\/?page_id=1047"},"modified":"2024-03-04T10:09:30","modified_gmt":"2024-03-04T09:09:30","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/food-pol.pl\/de\/datenschutzerklaerung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1047\" class=\"elementor elementor-1047\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-780e59d e-flex e-con-boxed e-con e-parent\" data-id=\"780e59d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a22cd00 e-flex e-con-boxed e-con e-child\" data-id=\"a22cd00\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e892846 elementor-widget elementor-widget-heading\" data-id=\"e892846\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Datenschutzerkl\u00e4rung<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7cffda3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7cffda3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a21874a\" data-id=\"a21874a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d89cc60 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d89cc60\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-02c9baf\" data-id=\"02c9baf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a8da75 elementor-widget elementor-widget-html\" data-id=\"0a8da75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p>Personenbezogene Daten (nachfolgend zumeist nur \u201eDaten\u201c genannt) werden von uns nur im Rahmen der Erforderlichkeit sowie zum Zwecke der Bereitstellung eines funktionsf\u00e4higen und nutzerfreundlichen Internetauftritts, inklusive seiner Inhalte und der dort angebotenen Leistungen, verarbeitet.<\/p>\r\n\r\n\r\n\r\n<p>Gem\u00e4\u00df Art. 4 Ziffer 1. der Verordnung (EU) 2016\/679, also der Datenschutz-Grundverordnung (nachfolgend nur \u201eDSGVO\u201c genannt), gilt als \u201eVerarbeitung\u201c jeder mit oder ohne Hilfe automatisierter Verfahren ausgef\u00fchrter Vorgang oder jede solche Vorgangsreihe im Zusammenhang mit personenbezogenen Daten, wie das Erheben, das Erfassen, die Organisation, das Ordnen, die Speicherung, die Anpassung oder Ver\u00e4nderung, das Auslesen, das Abfragen, die Verwendung, die Offenlegung durch \u00dcbermittlung, Verbreitung oder eine andere Form der Bereitstellung, den Abgleich oder die Verkn\u00fcpfung, die Einschr\u00e4nkung, das L\u00f6schen oder die Vernichtung.<\/p>\r\n\r\n\r\n\r\n<p>Mit der nachfolgenden Datenschutzerkl\u00e4rung informieren wir Sie insbesondere \u00fcber Art, Umfang, Zweck, Dauer und Rechtsgrundlage der Verarbeitung personenbezogener Daten, soweit wir entweder allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung entscheiden. Zudem informieren wir Sie nachfolgend \u00fcber die von uns zu Optimierungszwecken sowie zur Steigerung der Nutzungsqualit\u00e4t eingesetzten Fremdkomponenten, soweit hierdurch Dritte Daten in wiederum eigener Verantwortung verarbeiten.<\/p>\r\n\r\n\r\n\r\n<p>Unsere Datenschutzerkl\u00e4rung ist wie folgt gegliedert:<\/p>\r\n\r\n\r\n\r\n<p>I. Informationen \u00fcber uns als Verantwortliche<br>II. Rechte der Nutzer und Betroffenen<br>III. Informationen zur Datenverarbeitung<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">I. Informationen \u00fcber uns als Verantwortliche<\/h3>\r\n\r\n\r\n\r\n<p>Verantwortlicher Anbieter dieses Internetauftritts im datenschutzrechtlichen Sinne ist:<\/p>\r\n\r\n\r\n\r\nFood-Pol sp z o.o.<br>Gzik\u00f3w 9b<br>98-235 B\u0142aszki\r\n\r\n\r\n\r\n<p>Telefon: 604 741 869<br>E-Mail: biuro@food-pol.pl\r\n\r\n\r\n<h3 class=\"wp-block-heading\">II. Rechte der Nutzer und Betroffenen<\/h3>\r\n\r\n\r\n\r\n<p>Mit Blick auf die nachfolgend noch n\u00e4her beschriebene Datenverarbeitung haben die Nutzer und Betroffenen das Recht<\/p>\r\n\r\n\r\n\r\n<ul>\r\n<li>auf Best\u00e4tigung, ob sie betreffende Daten verarbeitet werden, auf Auskunft \u00fcber die verarbeiteten Daten, auf weitere Informationen \u00fcber die Datenverarbeitung sowie auf Kopien der Daten (vgl. auch Art. 15 DSGVO);<\/li>\r\n\r\n\r\n\r\n<li>auf Berichtigung oder Vervollst\u00e4ndigung unrichtiger bzw. unvollst\u00e4ndiger Daten (vgl. auch Art. 16 DSGVO);<\/li>\r\n\r\n\r\n\r\n<li>auf unverz\u00fcgliche L\u00f6schung der sie betreffenden Daten (vgl. auch Art. 17 DSGVO), oder, alternativ, soweit eine weitere Verarbeitung gem\u00e4\u00df Art. 17 Abs. 3 DSGVO erforderlich ist, auf Einschr\u00e4nkung der Verarbeitung nach Ma\u00dfgabe von Art. 18 DSGVO;<\/li>\r\n\r\n\r\n\r\n<li>auf Erhalt der sie betreffenden und von ihnen bereitgestellten Daten und auf \u00dcbermittlung dieser Daten an andere Anbieter\/Verantwortliche (vgl. auch Art. 20 DSGVO);<\/li>\r\n\r\n\r\n\r\n<li>auf Beschwerde gegen\u00fcber der Aufsichtsbeh\u00f6rde, sofern sie der Ansicht sind, dass die sie betreffenden Daten durch den Anbieter unter Versto\u00df gegen datenschutzrechtliche Bestimmungen verarbeitet werden (vgl. auch Art. 77 DSGVO).<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<p>Dar\u00fcber hinaus ist der Anbieter dazu verpflichtet, alle Empf\u00e4nger, denen gegen\u00fcber Daten durch den Anbieter offengelegt worden sind, \u00fcber jedwede Berichtigung oder L\u00f6schung von Daten oder die Einschr\u00e4nkung der Verarbeitung, die aufgrund der Artikel 16, 17 Abs. 1, 18 DSGVO erfolgt, zu unterrichten. Diese Verpflichtung besteht jedoch nicht, soweit diese Mitteilung unm\u00f6glich oder mit einem unverh\u00e4ltnism\u00e4\u00dfigen Aufwand verbunden ist. Unbeschadet dessen hat der Nutzer ein Recht auf Auskunft \u00fcber diese Empf\u00e4nger.<\/p>\r\n\r\n\r\n\r\n<p><strong>Ebenfalls haben die Nutzer und Betroffenen nach Art. 21 DSGVO das Recht auf Widerspruch gegen die k\u00fcnftige Verarbeitung der sie betreffenden Daten, sofern die Daten durch den Anbieter nach Ma\u00dfgabe von Art. 6 Abs. 1 lit. f) DSGVO verarbeitet werden. Insbesondere ist ein Widerspruch gegen die Datenverarbeitung zum Zwecke der Direktwerbung statthaft.<\/strong><\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">III. Informationen zur Datenverarbeitung<\/h3>\r\n\r\n\r\n\r\n<p>Ihre bei Nutzung unseres Internetauftritts verarbeiteten Daten werden gel\u00f6scht oder gesperrt, sobald der Zweck der Speicherung entf\u00e4llt, der L\u00f6schung der Daten keine gesetzlichen Aufbewahrungspflichten entgegenstehen und nachfolgend keine anderslautenden Angaben zu einzelnen Verarbeitungsverfahren gemacht werden.<\/p>\r\n<h4 class=\"jet-listing-dynamic-field__content\">Cookie Manager <\/h4><p>Zur Einholung einer Einwilligung zum Einsatz von technisch nicht notwendigen Cookies auf der Website, setzt der Anbieter einen Cookie-Manager ein.<\/p>\r\n<p>Bei dem Aufruf der Website wird ein Cookie mit den Einstellungsinformationen auf dem Endger\u00e4t des Nutzers abgelegt, sodass bei einem weiteren Besuch die Abfrage in Bezug auf die Einwilligung nicht erfolgen muss.<\/p>\r\n<p>Das Cookie ist erforderlich um eine rechtskonforme Einwilligung des Nutzers einzuholen.<\/p>\r\n<p>Die Installation der Cookies kann der Nutzer durch Einstellungen seines Browsers verhindern bzw. beenden.<\/p>\r\n<h4 class=\"jet-listing-dynamic-field__content\">Cookies<\/h4><h5>a) Sitzungs-Cookies\/Session-Cookies<\/h5>\r\n<p>Wir verwenden mit unserem Internetauftritt sog. Cookies. Cookies sind kleine Textdateien oder andere Speichertechnologien, die durch den von Ihnen eingesetzten Internet-Browser auf Ihrem Endger\u00e4t ablegt und gespeichert werden. Durch diese Cookies werden im individuellen Umfang bestimmte Informationen von Ihnen, wie beispielsweise Ihre Browser- oder Standortdaten oder Ihre IP-Adresse, verarbeitet.<\/p>\r\n<p>Durch diese Verarbeitung wird unser Internetauftritt benutzerfreundlicher, effektiver und sicherer, da die Verarbeitung bspw. die Wiedergabe unseres Internetauftritts in unterschiedlichen Sprachen oder das Angebot einer Warenkorbfunktion erm\u00f6glicht.<\/p>\r\n<p>Rechtsgrundlage dieser Verarbeitung ist Art. 6 Abs. 1 lit b.) DSGVO, sofern diese Cookies Daten zur Vertragsanbahnung oder Vertragsabwicklung verarbeitet werden.<\/p>\r\n<p>Falls die Verarbeitung nicht der Vertragsanbahnung oder Vertragsabwicklung dient, liegt unser berechtigtes Interesse in der Verbesserung der Funktionalit\u00e4t unseres Internetauftritts. Rechtsgrundlage ist in dann Art. 6 Abs. 1 lit. f) DSGVO.<\/p>\r\n<p>Mit Schlie\u00dfen Ihres Internet-Browsers werden diese Session-Cookies gel\u00f6scht.<\/p>\r\n<h5>b) Drittanbieter-Cookies<\/h5>\r\n<p>Gegebenenfalls werden mit unserem Internetauftritt auch Cookies von Partnerunternehmen, mit denen wir zum Zwecke der Werbung, der Analyse oder der Funktionalit\u00e4ten unseres Internetauftritts zusammenarbeiten, verwendet.<\/p>\r\n<p>Die Einzelheiten hierzu, insbesondere zu den Zwecken und den Rechtsgrundlagen der Verarbeitung solcher Drittanbieter-Cookies, entnehmen Sie bitte den nachfolgenden Informationen.<\/p>\r\n<h5>c) Beseitigungsm\u00f6glichkeit<\/h5>\r\n<p>Sie k\u00f6nnen die Installation der Cookies durch eine Einstellung Ihres Internet-Browsers verhindern oder einschr\u00e4nken. Ebenfalls k\u00f6nnen Sie bereits gespeicherte Cookies jederzeit l\u00f6schen. Die hierf\u00fcr erforderlichen Schritte und Ma\u00dfnahmen h\u00e4ngen jedoch von Ihrem konkret genutzten Internet-Browser ab. Bei Fragen benutzen Sie daher bitte die Hilfefunktion oder Dokumentation Ihres Internet-Browsers oder wenden sich an dessen Hersteller bzw. Support. Bei sog. Flash-Cookies kann die Verarbeitung allerdings nicht \u00fcber die Einstellungen des Browsers unterbunden werden. Stattdessen m\u00fcssen Sie insoweit die Einstellung Ihres Flash-Players \u00e4ndern. Auch die hierf\u00fcr erforderlichen Schritte und Ma\u00dfnahmen h\u00e4ngen von Ihrem konkret genutzten Flash-Player ab. Bei Fragen benutzen Sie daher bitte ebenso die Hilfefunktion oder Dokumentation Ihres Flash-Players oder wenden sich an den Hersteller bzw. Benutzer-Support.<\/p>\r\n<p>Sollten Sie die Installation der Cookies verhindern oder einschr\u00e4nken, kann dies allerdings dazu f\u00fchren, dass nicht s\u00e4mtliche Funktionen unseres Internetauftritts vollumf\u00e4nglich nutzbar sind.<\/p>\r\n<h4 class=\"jet-listing-dynamic-field__content\">Kontaktanfragen \/ Kontaktm\u00f6glichkeit<\/h4><p>Sofern Sie per Kontaktformular oder E-Mail mit uns in Kontakt treten, werden die dabei von Ihnen angegebenen Daten zur Bearbeitung Ihrer Anfrage genutzt. Die Angabe der Daten ist zur Bearbeitung und Beantwortung Ihre Anfrage erforderlich \u2013 ohne deren Bereitstellung k\u00f6nnen wir Ihre Anfrage nicht oder allenfalls eingeschr\u00e4nkt beantworten.<\/p>\r\n<p>Rechtsgrundlage f\u00fcr diese Verarbeitung ist Art. 6 Abs. 1 lit. b) DSGVO.<\/p>\r\n<p>Ihre Daten werden gel\u00f6scht, sofern Ihre Anfrage abschlie\u00dfend beantwortet worden ist und der L\u00f6schung keine gesetzlichen Aufbewahrungspflichten entgegenstehen, wie bspw. bei einer sich etwaig anschlie\u00dfenden Vertragsabwicklung.<\/p>\r\n<h4 class=\"jet-listing-dynamic-field__content\">Serverdaten<\/h4><p>Aus technischen Gr\u00fcnden, insbesondere zur Gew\u00e4hrleistung eines sicheren und stabilen Internetauftritts, werden Daten durch Ihren Internet-Browser an uns bzw. an unseren Webspace-Provider \u00fcbermittelt. Mit diesen sog. Server-Logfiles werden u.a. Typ und Version Ihres Internetbrowsers, das Betriebssystem, die Website, von der aus Sie auf unseren Internetauftritt gewechselt haben (Referrer URL), die Website(s) unseres Internetauftritts, die Sie besuchen, Datum und Uhrzeit des jeweiligen Zugriffs sowie die IP-Adresse des Internetanschlusses, von dem aus die Nutzung unseres Internetauftritts erfolgt, erhoben.<\/p>\r\n<p>Diese so erhobenen Daten werden vorr\u00fcbergehend gespeichert, dies jedoch nicht gemeinsam mit anderen Daten von Ihnen.<\/p>\r\n<p>Diese Speicherung erfolgt auf der Rechtsgrundlage von Art. 6 Abs. 1 lit. f) DSGVO. Unser berechtigtes Interesse liegt in der Verbesserung, Stabilit\u00e4t, Funktionalit\u00e4t und Sicherheit unseres Internetauftritts.<\/p>\r\n<p>Die Daten werden sp\u00e4testens nach sieben Tage wieder gel\u00f6scht, soweit keine weitere Aufbewahrung zu Beweiszwecken erforderlich ist. Andernfalls sind die Daten bis zur endg\u00fcltigen Kl\u00e4rung eines Vorfalls ganz oder teilweise von der L\u00f6schung ausgenommen.<\/p>\r\n<h4 class=\"jet-listing-dynamic-field__content\">Facebook<\/h4><p>Zur Bewerbung unserer Produkte und Leistungen sowie zur Kommunikation mit Interessenten oder Kunden betreiben wir eine Firmenpr\u00e4senz auf der Plattform Facebook.<\/p>\r\n<p>Auf dieser Social-Media-Plattform sind wir gemeinsam mit der Meta Platforms Ireland Limited, 4 Grand Canal Square, Dublin 2, Irland, verantwortlich.<\/p>\r\n<p>Der Datenschutzbeauftragte von Facebook kann \u00fcber ein Kontaktformular erreicht werden:<\/p>\r\n<p><a href=\"https:\/\/www.facebook.com\/help\/contact\/540977946302970\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/www.facebook.com\/help\/contact\/540977946302970<\/a><\/p>\r\n<p>Die gemeinsame Verantwortlichkeit haben wir in einer Vereinbarung bez\u00fcglich der jeweiligen Verpflichtungen im Sinne der DSGVO geregelt. Diese Vereinbarung, aus der sich die gegenseitigen Verpflichtungen ergeben, ist unter dem folgenden Link abrufbar:<\/p>\r\n<p><a href=\"https:\/\/www.facebook.com\/legal\/terms\/page_controller_addendum\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/www.facebook.com\/legal\/terms\/page_controller_addendum<\/a><\/p>\r\n<p>Rechtsgrundlage f\u00fcr die dadurch erfolgende und nachfolgend wiedergegebene Verarbeitung von personenbezogenen Daten ist Art. 6 Abs. 1 lit. f DSGVO. Unser berechtigtes Interesse besteht an der Analyse, der Kommunikation sowie dem Absatz und der Bewerbung unserer Produkte und Leistungen.<\/p>\r\n<p>Rechtsgrundlage kann auch eine Einwilligung des Nutzers gem\u00e4\u00df Art. 6 Abs. 1 lit. a DSGVO gegen\u00fcber dem Plattformbetreiber sein. Die Einwilligung hierzu kann der Nutzer nach Art. 7 Abs. 3 DSGVO jederzeit durch eine Mitteilung an den Plattformbetreiber f\u00fcr die Zukunft widerrufen.<\/p>\r\n<p>Bei dem Aufruf unseres Onlineauftritts auf der Plattform Facebook werden von der Facebook Ireland Ltd. als Betreiberin der Plattform in der EU Daten des Nutzers (z.B. pers\u00f6nliche Informationen, IP-Adresse etc.) verarbeitet.<\/p>\r\n<p>Diese Daten des Nutzers dienen zu statistischen Informationen \u00fcber die Inanspruchnahme unserer Firmenpr\u00e4senz auf Facebook. Die Facebook Ireland Ltd. nutzt diese Daten zu Marktforschungs- und Werbezwecken sowie zur Erstellung von Profilen der Nutzer. Anhand dieser Profile ist es der Facebook Ireland Ltd. beispielsweise m\u00f6glich, die Nutzer innerhalb und au\u00dferhalb von Facebook interessenbezogen zu bewerben. Ist der Nutzer zum Zeitpunkt des Aufrufes in seinem Account auf Facebook eingeloggt, kann die Facebook Ireland Ltd. zudem die Daten mit dem jeweiligen Nutzerkonto verkn\u00fcpfen.<\/p>\r\n<p>Im Falle einer Kontaktaufnahme des Nutzers \u00fcber Facebook werden die bei dieser Gelegenheit eingegebenen personenbezogenen Daten des Nutzers zur Bearbeitung der Anfrage genutzt. Die Daten des Nutzers werden bei uns gel\u00f6scht, sofern die Anfrage des Nutzers abschlie\u00dfend beantwortet wurde und keine gesetzlichen Aufbewahrungspflichten, wie z.B. bei einer anschlie\u00dfenden Vertragsabwicklung, entgegenstehen.<\/p>\r\n<p>Zur Verarbeitung der Daten werden von der Facebook Ireland Ltd. ggf. auch Cookies gesetzt.<\/p>\r\n<p>Sollte der Nutzer mit dieser Verarbeitung nicht einverstanden sein, so besteht die M\u00f6glichkeit, die Installation der Cookies durch eine entsprechende Einstellung des Browsers zu verhindern. Bereits gespeicherte Cookies k\u00f6nnen ebenfalls jederzeit gel\u00f6scht werden. Die Einstellungen hierzu sind vom jeweiligen Browser abh\u00e4ngig. Bei Flash-Cookies l\u00e4sst sich die Verarbeitung nicht \u00fcber die Einstellungen des Browsers unterbinden, sondern durch die entsprechende Einstellung des Flash-Players. Sollte der Nutzer die Installation der Cookies verhindern oder einschr\u00e4nken, kann dies dazu f\u00fchren, dass nicht s\u00e4mtliche Funktionen von Facebook vollumf\u00e4nglich nutzbar sind.<\/p>\r\n<p>N\u00e4heres zu den Verarbeitungst\u00e4tigkeiten, deren Unterbindung und zur L\u00f6schung der von Facebook verarbeiteten Daten finden sich in der Datenrichtlinie von Facebook:<\/p>\r\n<p><a href=\"https:\/\/www.facebook.com\/privacy\/explanation\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/www.facebook.com\/privacy\/explanation<\/a><\/p>\r\n<p>Es ist nicht ausgeschlossen, dass die Verarbeitung durch die Meta Platforms Ireland Limited auch \u00fcber die Meta Platforms, Inc., 1601 Willow Road, Menlo Park, California 94025 in den USA erfolgt.<\/p>\r\n<h4 class=\"jet-listing-dynamic-field__content\">Allgemeine Verlinkung auf Profile bei Drittanbietern<\/h4><p>Der Anbieter setzt auf der Website eine Verlinkung auf die nachstehend aufgef\u00fchrten sozialen Netzwerke ein.<\/p>\r\n<p>Rechtsgrundlage ist hierbei Art. 6 Abs. 1 lit. f DSGVO. Das berechtigte Interesse des Anbieters besteht an der Verbesserung der Nutzungsqualit\u00e4t der Website.<\/p>\r\n<p>Die Einbindung der Plugins erfolgt dabei \u00fcber eine verlinkte Grafik. Erst durch einen Klick auf die entsprechende Grafik wird der Nutzer zu dem Dienst des jeweiligen sozialen Netzwerks weitergeleitet.<\/p>\r\n<p>Nach der Weiterleitung des Kunden werden durch das jeweilige Netzwerk Informationen \u00fcber den Nutzer erfasst. Dies sind zun\u00e4chst Daten wie IP-Adresse, Datum, Uhrzeit und besuchte Seite. Ist der Nutzer w\u00e4hrenddessen in seinem Benutzerkonto des jeweiligen Netzwerks eingeloggt, kann der Netzwerk-Betreiber ggf. die gesammelten Informationen des konkreten Besuches des Nutzers dem pers\u00f6nlichen Account des Nutzers zuordnen. Interagiert der Nutzer \u00fcber einen \u201eTeilen\u201c-Button des jeweiligen Netzwerks, k\u00f6nnen diese Informationen in dem pers\u00f6nlichen Benutzerkonto des Nutzers gespeichert und ggf. ver\u00f6ffentlicht werden. Will der Nutzer verhindern, dass die gesammelten Informationen unmittelbar seinem Benutzerkonto zugeordnet werden, muss sich der Nutzer vor dem Anklicken der Grafik ausloggen. Zudem besteht die M\u00f6glichkeit, das jeweilige Benutzerkonto entsprechend zu konfigurieren.<\/p>\r\n<p>Folgende soziale Netzwerke sind vom Anbieter verlinkt:<\/p>\r\n<h4 class=\"jet-listing-dynamic-field__content\">facebook<\/h4><p>Meta Platforms Ireland Limited, 4 Grand Canal Square, Dublin 2, Irland.<\/p>\r\n<p>Datenschutzerkl\u00e4rung: <a href=\"https:\/\/www.facebook.com\/policy.php\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/www.facebook.com\/policy.php<\/a><\/p>\r\n<h4 class=\"jet-listing-dynamic-field__content\">Google Analytics<\/h4><p>In unserem Internetauftritt setzen wir Google Analytics ein. Hierbei handelt es sich um einen Webanalysedienst der Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irland, nachfolgend nur \u201eGoogle\u201c genannt.<\/p>\r\n<p>Der Dienst Google Analytics dient zur Analyse des Nutzungsverhaltens unseres Internetauftritts. Rechtsgrundlage ist Art. 6 Abs. 1 lit. f) DSGVO. Unser berechtigtes Interesse liegt in der Analyse, Optimierung und dem wirtschaftlichen Betrieb unseres Internetauftritts.<\/p>\r\n<p>Nutzungs- und nutzerbezogene Informationen, wie bspw. IP-Adresse, Ort, Zeit oder H\u00e4ufigkeit des Besuchs unseres Internetauftritts, werden dabei an einen Server von Google in den USA \u00fcbertragen und dort gespeichert. Allerdings nutzen wir Google Analytics mit der sog. Anonymisierungsfunktion. Durch diese Funktion k\u00fcrzt Google die IP-Adresse schon innerhalb der EU bzw. des EWR.<\/p>\r\n<p>Die so erhobenen Daten werden wiederum von Google genutzt, um uns eine Auswertung \u00fcber den Besuch unseres Internetauftritts sowie \u00fcber die dortigen Nutzungsaktivit\u00e4ten zur Verf\u00fcgung zu stellen. Auch k\u00f6nnen diese Daten genutzt werden, um weitere Dienstleistungen zu erbringen, die mit der Nutzung unseres Internetauftritts und der Nutzung des Internets zusammenh\u00e4ngen.<\/p>\r\n<p>Google gibt an, Ihre IP-Adresse nicht mit anderen Daten zu verbinden. Zudem h\u00e4lt Google unter<\/p>\r\n<p><a href=\"https:\/\/www.google.com\/intl\/de\/policies\/privacy\/partners\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/www.google.com\/intl\/de\/policies\/privacy\/partners<\/a><\/p>\r\n<p>weitere datenschutzrechtliche Informationen f\u00fcr Sie bereit, so bspw. auch zu den M\u00f6glichkeiten, die Datennutzung zu unterbinden.<\/p>\r\n<p>Zudem bietet Google unter<\/p>\r\n<p><a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de<\/a><\/p>\r\n<p>ein sog. Deaktivierungs-Add-on nebst weiteren Informationen hierzu an. Dieses Add-on l\u00e4sst sich mit den g\u00e4ngigen Internet-Browsern installieren und bietet Ihnen weitergehende Kontrollm\u00f6glichkeit \u00fcber die Daten, die Google bei Aufruf unseres Internetauftritts erfasst. Dabei teilt das Add-on dem JavaScript (ga.js) von Google Analytics mit, dass Informationen zum Besuch unseres Internetauftritts nicht an Google Analytics \u00fcbermittelt werden sollen. Dies verhindert aber nicht, dass Informationen an uns oder an andere Webanalysedienste \u00fcbermittelt werden. Ob und welche weiteren Webanalysedienste von uns eingesetzt werden, erfahren Sie nat\u00fcrlich ebenfalls in dieser Datenschutzerkl\u00e4rung.<\/p>\r\n<h4 class=\"jet-listing-dynamic-field__content\">Google Fonts<\/h4><p>In unserem Internetauftritt setzen wir Google Fonts zur Darstellung externer Schriftarten ein. Es handelt sich hierbei um einen Dienst der Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irland, nachfolgend nur \u201eGoogle\u201c genannt.<\/p>\r\n<p>Um die Darstellung bestimmter Schriften in unserem Internetauftritt zu erm\u00f6glichen, wird bei Aufruf unseres Internetauftritts eine Verbindung zu dem Google-Server in den USA aufgebaut.<\/p>\r\n<p>Rechtsgrundlage ist Art. 6 Abs. 1 lit. f) DSGVO. Unser berechtigtes Interesse liegt in der Optimierung und dem wirtschaftlichen Betrieb unseres Internetauftritts.<\/p>\r\n<p>Durch die bei Aufruf unseres Internetauftritts hergestellte Verbindung zu Google kann Google ermitteln, von welcher Website Ihre Anfrage gesendet worden ist und an welche IP-Adresse die Darstellung der Schrift zu \u00fcbermitteln ist.<\/p>\r\n<p>Google bietet unter<\/p>\r\n<p><a href=\"https:\/\/adssettings.google.com\/authenticated\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/adssettings.google.com\/authenticated<\/a><\/p>\r\n<p><a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/policies.google.com\/privacy<\/a><\/p>\r\n<p>weitere Informationen an und zwar insbesondere zu den M\u00f6glichkeiten der Unterbindung der Datennutzung.<\/p>\r\n\r\n<p><a href=\"https:\/\/www.generator-datenschutzerkl\u00e4rung.de\" target=\"_blank\" rel=\"noopener\">Muster-Datenschutzerkl\u00e4rung<\/a> der <a href=\"https:\/\/www.bewertung-l\u00f6schen24.de\" rel=\"nofollow noopener\" target=\"_blank\">Anwaltskanzlei Wei\u00df &amp; Partner<\/a><\/p>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Personenbezogene Daten (nachfolgend zumeist nur \u201eDaten\u201c genannt) werden von uns nur im Rahmen der Erforderlichkeit sowie zum Zwecke der Bereitstellung eines funktionsf\u00e4higen und nutzerfreundlichen Internetauftritts, inklusive seiner Inhalte und der dort angebotenen Leistungen, verarbeitet. Gem\u00e4\u00df Art. 4 Ziffer 1. der Verordnung (EU) 2016\/679, also der Datenschutz-Grundverordnung (nachfolgend nur \u201eDSGVO\u201c genannt), gilt als \u201eVerarbeitung\u201c jeder mit [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1047","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/food-pol.pl\/de\/wp-json\/wp\/v2\/pages\/1047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/food-pol.pl\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/food-pol.pl\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/food-pol.pl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/food-pol.pl\/de\/wp-json\/wp\/v2\/comments?post=1047"}],"version-history":[{"count":10,"href":"https:\/\/food-pol.pl\/de\/wp-json\/wp\/v2\/pages\/1047\/revisions"}],"predecessor-version":[{"id":1256,"href":"https:\/\/food-pol.pl\/de\/wp-json\/wp\/v2\/pages\/1047\/revisions\/1256"}],"wp:attachment":[{"href":"https:\/\/food-pol.pl\/de\/wp-json\/wp\/v2\/media?parent=1047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}